{"id":32,"count":1,"description":"","link":"https:\/\/chaitanyas-academy.com\/blog\/tag\/iit-jee-classes-in-pune","name":"IIT JEE Classes In Pune","slug":"iit-jee-classes-in-pune","taxonomy":"post_tag","meta":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>IIT JEE Classes In Pune Archives - Chaitanyas Academy Blog<\/title>\n<meta name=\"robots\" content=\"noindex, follow\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"IIT JEE Classes In Pune Archives - Chaitanyas Academy Blog\" \/>\n<meta property=\"og:url\" content=\"https:\/\/chaitanyas-academy.com\/blog\/tag\/iit-jee-classes-in-pune\" \/>\n<meta property=\"og:site_name\" content=\"Chaitanyas Academy Blog\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\\\/\\\/chaitanyas-academy.com\\\/blog\\\/tag\\\/iit-jee-classes-in-pune\",\"url\":\"https:\\\/\\\/chaitanyas-academy.com\\\/blog\\\/tag\\\/iit-jee-classes-in-pune\",\"name\":\"IIT JEE Classes In Pune Archives - Chaitanyas Academy Blog\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/chaitanyas-academy.com\\\/blog\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/chaitanyas-academy.com\\\/blog\\\/tag\\\/iit-jee-classes-in-pune#breadcrumb\"},\"inLanguage\":\"en-US\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/chaitanyas-academy.com\\\/blog\\\/tag\\\/iit-jee-classes-in-pune#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/chaitanyas-academy.com\\\/blog\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"IIT JEE Classes In Pune\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/chaitanyas-academy.com\\\/blog\\\/#website\",\"url\":\"https:\\\/\\\/chaitanyas-academy.com\\\/blog\\\/\",\"name\":\"Chaitanyas Academy Blog\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/chaitanyas-academy.com\\\/blog\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"IIT JEE Classes In Pune Archives - Chaitanyas Academy Blog","robots":{"index":"noindex","follow":"follow"},"og_locale":"en_US","og_type":"article","og_title":"IIT JEE Classes In Pune Archives - Chaitanyas Academy Blog","og_url":"https:\/\/chaitanyas-academy.com\/blog\/tag\/iit-jee-classes-in-pune","og_site_name":"Chaitanyas Academy Blog","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/chaitanyas-academy.com\/blog\/tag\/iit-jee-classes-in-pune","url":"https:\/\/chaitanyas-academy.com\/blog\/tag\/iit-jee-classes-in-pune","name":"IIT JEE Classes In Pune Archives - Chaitanyas Academy Blog","isPartOf":{"@id":"https:\/\/chaitanyas-academy.com\/blog\/#website"},"breadcrumb":{"@id":"https:\/\/chaitanyas-academy.com\/blog\/tag\/iit-jee-classes-in-pune#breadcrumb"},"inLanguage":"en-US"},{"@type":"BreadcrumbList","@id":"https:\/\/chaitanyas-academy.com\/blog\/tag\/iit-jee-classes-in-pune#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/chaitanyas-academy.com\/blog\/"},{"@type":"ListItem","position":2,"name":"IIT JEE Classes In Pune"}]},{"@type":"WebSite","@id":"https:\/\/chaitanyas-academy.com\/blog\/#website","url":"https:\/\/chaitanyas-academy.com\/blog\/","name":"Chaitanyas Academy Blog","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/chaitanyas-academy.com\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"}]}},"_links":{"self":[{"href":"https:\/\/chaitanyas-academy.com\/blog\/wp-json\/wp\/v2\/tags\/32","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/chaitanyas-academy.com\/blog\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/chaitanyas-academy.com\/blog\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/chaitanyas-academy.com\/blog\/wp-json\/wp\/v2\/posts?tags=32"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}